{"id":11125,"date":"2024-09-19T19:59:04","date_gmt":"2024-09-19T17:59:04","guid":{"rendered":"https:\/\/www.carlovirgilio.it\/?post_type=opera&#038;p=11125"},"modified":"2024-09-26T11:14:01","modified_gmt":"2024-09-26T09:14:01","slug":"giulio-aristide-sartorio-sphinx-scylla-and-charybdis","status":"publish","type":"opera","link":"https:\/\/www.carlovirgilio.it\/en\/opera\/giulio-aristide-sartorio-sphinx-scylla-and-charybdis\/","title":{"rendered":"Giulio Aristide Sartorio &#8211; Sphinx \/ Scylla and Charybdis"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#d0d7da&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;11174&#8243; img_size=&#8221;large&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text el_class=&#8221;wpb_text_autore-opera&#8221;]<\/p>\n<h3>Giulio Aristide Sartorio<\/h3>\n<p>Rome 1860-1932[\/vc_column_text][vc_text_separator title=&#8221;&#8221; i_icon_fontawesome=&#8221;far fa-object-group&#8221; i_color=&#8221;grey&#8221; i_size=&#8221;sm&#8221; align=&#8221;align_left&#8221; color=&#8221;custom&#8221; el_width=&#8221;70&#8243; add_icon=&#8221;true&#8221; accent_color=&#8221;#d0d7da&#8221;][vc_column_text]<\/p>\n<h3 style=\"text-align: justify;\"><i>Sphinx \/ Scylla and Charybdis <\/i>\u2022 1890-95 ca.<\/h3>\n<p style=\"text-align: justify;\">mixed technique on prepared paper, 290 x 300 mm<\/p>\n<p style=\"text-align: justify;\">GAS monogram at bottom left<\/p>\n<p style=\"text-align: justify;\">Bibliography: <em>Scilla e Cariddi. Pubblicazione dell\u2019Associazione della Stampa Periodica Italiana a beneficio del Patronato Regina Elena per gli orfani del terremoto<\/em>, Roma 1909, illustrato al quarto di copertina; G. Barbera, <em>Gli anni dimenticati. Pittori a Messina tra Otto e Novecento<\/em>, catalogo della mostra (Messina, Museo Regionale, 1998), Messina 1998, cat. n. 80, p. 159; P.A. De Rosa, P.E. Trastulli (a cura di), <em>Giulio Aristide Sartorio. Il realismo plastico tra sentimento ed intelletto<\/em>, catalogo della mostra (Orvieto, Palazzo Coelli, 2005), Orvieto 2005, cat. n. 3, p. 17; R. Miracco (a cura di), <em>Giulio Aristide Sartorio. 1860-1932<\/em>, catalogo della mostra (Roma, Chiostro del Bramante, 2006), Firenze 2006, p. 181.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#d0d7da&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;11174&#8243; img_size=&#8221;large&#8221; onclick=&#8221;img_link_large&#8221; img_link_target=&#8221;_blank&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text el_class=&#8221;wpb_text_autore-opera&#8221;] Giulio Aristide Sartorio Rome 1860-1932[\/vc_column_text][vc_text_separator title=&#8221;&#8221; i_icon_fontawesome=&#8221;far fa-object-group&#8221; i_color=&#8221;grey&#8221; i_size=&#8221;sm&#8221; align=&#8221;align_left&#8221; color=&#8221;custom&#8221; el_width=&#8221;70&#8243; add_icon=&#8221;true&#8221; accent_color=&#8221;#d0d7da&#8221;][vc_column_text] Sphinx \/ Scylla and Charybdis \u2022 1890-95 ca. mixed technique on prepared paper, 290 x 300 mm GAS monogram at bottom left Bibliography: Scilla e Cariddi. Pubblicazione dell\u2019Associazione della Stampa&hellip;<\/p>\n","protected":false},"featured_media":11175,"template":"","autore":[165],"tipologia_opera":[96],"ambito_opera":[90],"data_opera":[286],"disponibilita_opera":[479],"titolo_mostra":[],"tag_mostra":[],"class_list":["post-11125","opera","type-opera","status-publish","has-post-thumbnail","hentry","autore-giulio-aristide-sartorio-1860-1932","tipologia_opera-recent-sells","ambito_opera-disegno-en","data_opera-286","disponibilita_opera-disponibilie","description-off"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/opera\/11125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/opera"}],"about":[{"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/types\/opera"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/media\/11175"}],"wp:attachment":[{"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/media?parent=11125"}],"wp:term":[{"taxonomy":"autore","embeddable":true,"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/autore?post=11125"},{"taxonomy":"tipologia_opera","embeddable":true,"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/tipologia_opera?post=11125"},{"taxonomy":"ambito_opera","embeddable":true,"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/ambito_opera?post=11125"},{"taxonomy":"data_opera","embeddable":true,"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/data_opera?post=11125"},{"taxonomy":"disponibilita_opera","embeddable":true,"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/disponibilita_opera?post=11125"},{"taxonomy":"titolo_mostra","embeddable":true,"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/titolo_mostra?post=11125"},{"taxonomy":"tag_mostra","embeddable":true,"href":"https:\/\/www.carlovirgilio.it\/en\/wp-json\/wp\/v2\/tag_mostra?post=11125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}